{"id":123,"date":"2019-06-17T21:01:18","date_gmt":"2019-06-18T02:01:18","guid":{"rendered":"https:\/\/atrevete.academy\/blog\/?p=123"},"modified":"2021-07-20T20:44:50","modified_gmt":"2021-07-21T01:44:50","slug":"emprender-con-exito-y-no-morir-tratando","status":"publish","type":"post","link":"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/","title":{"rendered":"Emprender con \u00e9xito sin morir en el intento"},"content":{"rendered":"<p>C\u00f3mo emprender con \u00e9xito es una interrogante que cada vez m\u00e1s cobra importancia en la mentalidad de las personas, sobre todo si nos situamos en una realidad en la que la tasa de desempleo de la poblaci\u00f3n puede llegar a ser del 6.5% s\u00f3lo en Lima Metropolitana.<\/p>\n<p>Atreverse a abrir una empresa propia no es cosa f\u00e1cil, de hecho es un camino largo y lleno de dificultades que pueden desmotivar a muchos de los que lo est\u00e1n considerando.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_73 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a03f240c487b\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a03f240c487b\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/#5_Tips_para_que_emprender_con_exito_y_no_morir_en_el_intento\" title=\"5 Tips para que emprender con \u00e9xito y no morir en el intento\">5 Tips para que emprender con \u00e9xito y no morir en el intento<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"5_Tips_para_que_emprender_con_exito_y_no_morir_en_el_intento\"><\/span>5 Tips para que emprender con \u00e9xito y no morir en el intento<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Es cierto que es dif\u00edcil, pero si te apasiona tu idea y est\u00e1s dispuesto a intentarlo, aqu\u00ed te<br \/>\ndejamos algunos tips:<\/p>\n<p>1. No es un camino f\u00e1cil y si no est\u00e1s dispuesto a persistir, no es una buena idea que<br \/>\nconsideres dejar tu trabajo para emprender una empresa propia porque lo m\u00e1s probable<br \/>\nes que termines desistiendo frente a las dificultades que s\u00ed o s\u00ed se te van a presentar.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/atrevete.academy\/taller-publicidad-en-facebook-y-chatbot\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2282 size-full\" src=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage.jpg\" alt=\"\" width=\"1920\" height=\"960\" srcset=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage.jpg 1920w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-300x150.jpg 300w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-1024x512.jpg 1024w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-768x384.jpg 768w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-1536x768.jpg 1536w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-696x348.jpg 696w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-1068x534.jpg 1068w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-840x420.jpg 840w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>2. Define tu idea de negocio. Hay que ser muy cuidadosos a la hora de elegir una idea de<br \/>\nnegocio y analizar si es que esta es la adecuada. En un mercado de por s\u00ed<br \/>\nsobre saturado y en el que 8 de 10 emprendimientos fracasan en un periodo de 5 a\u00f1os, tener una idea que destaque de las ya existentes te ayudar\u00e1 a presentar una empresa<br \/>\natractiva a tus potenciales clientes.<\/p>\n<p>3. Rod\u00e9ate del equipo adecuado. Si bien al inicio tu equipo ser\u00e1 reducido, aseg\u00farate de<br \/>\nestar alineado con tu equipo en la b\u00fasqueda de un mismo objetivo y de tener la misma<br \/>\npasi\u00f3n por la empresa que buscan llevar al \u00e9xito.<\/p>\n<p>4. No pases por alto tu plan de negocios. Es un punto clave que te ayudar\u00e1 a tener en<br \/>\norden todo lo relacionado a tu empresa, desde tu identidad, tus objetivos y hasta tu<br \/>\npresupuesto. Aseg\u00farate de redactar un plan de negocio que te servir\u00e1 como columna<br \/>\nvertebral cuando tu empresa comience a crecer.<\/p>\n<p>5. Ten una estrategia digital. La forma de hacer marketing ha cambiado mucho en los<br \/>\n\u00faltimos a\u00f1os y las plataformas digitales han cobrado importancia fundamental a la hora<br \/>\nde presentarte con tu p\u00fablico objetivo por lo que no puedes descuidar este medio<br \/>\ncuando busques aplicar una estrategia de marketing para tu negocio.<\/p>\n<p><a href=\"https:\/\/atrevete.academy\/taller-publicidad-en-facebook-y-chatbot\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-399 size-full\" src=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/SOCIAL-SELLING.png\" alt=\"\" width=\"728\" height=\"90\" srcset=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/SOCIAL-SELLING.png 728w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/SOCIAL-SELLING-300x37.png 300w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/SOCIAL-SELLING-696x86.png 696w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00f3mo emprender con \u00e9xito es una interrogante que cada vez m\u00e1s cobra importancia en la mentalidad de las personas, sobre todo si nos situamos en una realidad en la que la tasa de desempleo de la poblaci\u00f3n puede llegar a ser del 6.5% s\u00f3lo en Lima Metropolitana. Atreverse a abrir una empresa propia no es [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":{"0":"post-123","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-emprendimiento"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Emprender con \u00e9xito sin morir en el intento - BLOG |<\/title>\n<meta name=\"description\" content=\"Atreverse a abrir una empresa propia no es f\u00e1cil pero tampoco es imposible. Aqu\u00ed te dejamos los tips m\u00e1s importantes para emprender con \u00e9xito.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emprender con \u00e9xito sin morir en el intento - BLOG |\" \/>\n<meta property=\"og:description\" content=\"Atreverse a abrir una empresa propia no es f\u00e1cil pero tampoco es imposible. Aqu\u00ed te dejamos los tips m\u00e1s importantes para emprender con \u00e9xito.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG |\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/atrevete.academy\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-18T02:01:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-21T01:44:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/failure.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Atrevete Academia de Marketing Digital\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Atrevete Academia de Marketing Digital\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/\",\"url\":\"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/\",\"name\":\"Emprender con \u00e9xito sin morir en el intento - BLOG |\",\"isPartOf\":{\"@id\":\"https:\/\/atrevete.academy\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/failure.jpg\",\"datePublished\":\"2019-06-18T02:01:18+00:00\",\"dateModified\":\"2021-07-21T01:44:50+00:00\",\"author\":{\"@id\":\"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/bb788b3a3a7e028ab3e0ef0bee458530\"},\"description\":\"Atreverse a abrir una empresa propia no es f\u00e1cil pero tampoco es imposible. Aqu\u00ed te dejamos los tips m\u00e1s importantes para emprender con \u00e9xito.\",\"breadcrumb\":{\"@id\":\"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/#primaryimage\",\"url\":\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/failure.jpg\",\"contentUrl\":\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/failure.jpg\",\"width\":600,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/atrevete.academy\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emprender con \u00e9xito sin morir en el intento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/atrevete.academy\/blog\/#website\",\"url\":\"https:\/\/atrevete.academy\/blog\/\",\"name\":\"BLOG |\",\"description\":\"Atr\u00e9vete Academia de Marketing Digital\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/atrevete.academy\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/bb788b3a3a7e028ab3e0ef0bee458530\",\"name\":\"Atrevete Academia de Marketing Digital\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2aa8c69a94e65335eb5772ab1a3e4e029bd82daac9574263c5505cd6afa2c377?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2aa8c69a94e65335eb5772ab1a3e4e029bd82daac9574263c5505cd6afa2c377?s=96&d=mm&r=g\",\"caption\":\"Atrevete Academia de Marketing Digital\"},\"description\":\"Atr\u00e9vete Academia de Marketing Digital busca ser tu aliado a la hora de aprender y aplicar las nuevas t\u00e9cnicas del Marketing Digital que te permitir\u00e1n entender a tus clientes y as\u00ed realizar estrategias efectivas que te ayudar\u00e1n a potenciar tus habilidades y las de tu empresa.\",\"sameAs\":[\"https:\/\/www.facebook.com\/atrevete.academy\/\",\"https:\/\/www.instagram.com\/atrevete_academy\/\"],\"url\":\"https:\/\/atrevete.academy\/blog\/author\/atrevete-academia-de-marketing-digital\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emprender con \u00e9xito sin morir en el intento - BLOG |","description":"Atreverse a abrir una empresa propia no es f\u00e1cil pero tampoco es imposible. Aqu\u00ed te dejamos los tips m\u00e1s importantes para emprender con \u00e9xito.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/","og_locale":"es_ES","og_type":"article","og_title":"Emprender con \u00e9xito sin morir en el intento - BLOG |","og_description":"Atreverse a abrir una empresa propia no es f\u00e1cil pero tampoco es imposible. Aqu\u00ed te dejamos los tips m\u00e1s importantes para emprender con \u00e9xito.","og_url":"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/","og_site_name":"BLOG |","article_author":"https:\/\/www.facebook.com\/atrevete.academy\/","article_published_time":"2019-06-18T02:01:18+00:00","article_modified_time":"2021-07-21T01:44:50+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/failure.jpg","type":"image\/jpeg"}],"author":"Atrevete Academia de Marketing Digital","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Atrevete Academia de Marketing Digital","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/","url":"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/","name":"Emprender con \u00e9xito sin morir en el intento - BLOG |","isPartOf":{"@id":"https:\/\/atrevete.academy\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/#primaryimage"},"image":{"@id":"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/#primaryimage"},"thumbnailUrl":"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/failure.jpg","datePublished":"2019-06-18T02:01:18+00:00","dateModified":"2021-07-21T01:44:50+00:00","author":{"@id":"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/bb788b3a3a7e028ab3e0ef0bee458530"},"description":"Atreverse a abrir una empresa propia no es f\u00e1cil pero tampoco es imposible. Aqu\u00ed te dejamos los tips m\u00e1s importantes para emprender con \u00e9xito.","breadcrumb":{"@id":"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/#primaryimage","url":"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/failure.jpg","contentUrl":"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/06\/failure.jpg","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/atrevete.academy\/blog\/emprender-con-exito-y-no-morir-tratando\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/atrevete.academy\/blog\/"},{"@type":"ListItem","position":2,"name":"Emprender con \u00e9xito sin morir en el intento"}]},{"@type":"WebSite","@id":"https:\/\/atrevete.academy\/blog\/#website","url":"https:\/\/atrevete.academy\/blog\/","name":"BLOG |","description":"Atr\u00e9vete Academia de Marketing Digital","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atrevete.academy\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/bb788b3a3a7e028ab3e0ef0bee458530","name":"Atrevete Academia de Marketing Digital","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2aa8c69a94e65335eb5772ab1a3e4e029bd82daac9574263c5505cd6afa2c377?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2aa8c69a94e65335eb5772ab1a3e4e029bd82daac9574263c5505cd6afa2c377?s=96&d=mm&r=g","caption":"Atrevete Academia de Marketing Digital"},"description":"Atr\u00e9vete Academia de Marketing Digital busca ser tu aliado a la hora de aprender y aplicar las nuevas t\u00e9cnicas del Marketing Digital que te permitir\u00e1n entender a tus clientes y as\u00ed realizar estrategias efectivas que te ayudar\u00e1n a potenciar tus habilidades y las de tu empresa.","sameAs":["https:\/\/www.facebook.com\/atrevete.academy\/","https:\/\/www.instagram.com\/atrevete_academy\/"],"url":"https:\/\/atrevete.academy\/blog\/author\/atrevete-academia-de-marketing-digital\/"}]}},"_links":{"self":[{"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/posts\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/comments?post=123"}],"version-history":[{"count":15,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/posts\/123\/revisions"}],"predecessor-version":[{"id":3240,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/posts\/123\/revisions\/3240"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/media\/125"}],"wp:attachment":[{"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/media?parent=123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/categories?post=123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/tags?post=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}