{"id":1567,"date":"2020-04-15T11:49:39","date_gmt":"2020-04-15T16:49:39","guid":{"rendered":"https:\/\/atrevete.academy\/blog\/?p=1567"},"modified":"2020-11-03T19:37:54","modified_gmt":"2020-11-04T00:37:54","slug":"el-e-commerce-en-tiempos-de-coronavirus","status":"publish","type":"post","link":"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/","title":{"rendered":"El E-Commerce en tiempos de Coronavirus"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Nos estamos acercando al mes desde que entramos en <strong>aislamiento social obligatorio<\/strong> a causa de la llegada del <strong>coronavirus<\/strong> al pa\u00eds y, a consecuencia de ello, muchas personas que se encuentran en <strong>el sector del e-commerce<\/strong>, tanto para una empresa grande como para una independiente, se preguntan \u00bfc\u00f3mo pueden seguir incrementando o manteniendo sus ventas frente a esta nueva situaci\u00f3n que ha afectado a muchos negocios a nivel mundial?.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1568 aligncenter\" src=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/modern-flat-design-concept-online-shopping-with-small-people-mobile-website-development-ui-ux-design_183665-14.jpg\" alt=\"\" width=\"626\" height=\"455\" srcset=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/modern-flat-design-concept-online-shopping-with-small-people-mobile-website-development-ui-ux-design_183665-14.jpg 626w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/modern-flat-design-concept-online-shopping-with-small-people-mobile-website-development-ui-ux-design_183665-14-300x218.jpg 300w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/modern-flat-design-concept-online-shopping-with-small-people-mobile-website-development-ui-ux-design_183665-14-324x235.jpg 324w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/modern-flat-design-concept-online-shopping-with-small-people-mobile-website-development-ui-ux-design_183665-14-578x420.jpg 578w\" sizes=\"auto, (max-width: 626px) 100vw, 626px\" \/><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_73 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenidos<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a58156cc06d9\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a58156cc06d9\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#%C2%BFQue_sucede_con_el_E-Commerce_en_este_momento\" title=\"\u00bfQu\u00e9 sucede con el E-Commerce en este momento?\">\u00bfQu\u00e9 sucede con el E-Commerce en este momento?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#En_conclusion\" title=\"En conclusi\u00f3n,\">En conclusi\u00f3n,<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_sucede_con_el_E-Commerce_en_este_momento\"><\/span>\u00bfQu\u00e9 sucede con el E-Commerce en este momento?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Entendemos que hasta este punto es un poco inc\u00f3modo, y frustrante, el <strong>tener que salir de casa solo<\/strong> para poder realizar, \u00fanicamente,<strong> sus compras diarias<\/strong> y\/o <strong>pasear a tu mascota<\/strong> bajo un <strong>tiempo limitado<\/strong>. Pero sabemos que uno de los grupos de personas m\u00e1s afectadas, entre muchos m\u00e1s, \u00a0son<strong> los comerciantes <\/strong>(personas que se dediquen a diferentes tipos de comercio); sin embargo, esta situaci\u00f3n <strong>no ha impedido<\/strong> que <strong>las ventas online<\/strong> se detengan y se eliminen por completo.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Debido a la cuarentena, muchos de los empresarios que se encuentran en el sector e-commerce han optado por desplegar<strong style=\"font-weight: 400;\"> una estrategia de\u00a0<\/strong><b>marketing<\/b>\u00a0determinada y enfocada, principalmente, en <a href=\"https:\/\/atrevete.academy\/blog\/marketing-de-contenidos\/\"><strong>el marketing de contenidos<\/strong><\/a>.\u00a0<span style=\"font-weight: 400;\">Como, por ejemplo, ejecutando <strong>descuentos y\/o sorteos<\/strong> con el prop\u00f3sito de mantener a sus <strong>clientes interactivos e interesados en sus productos<\/strong> y\/o servicios que presenta la marca durante este tiempo de aislamiento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"> <img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1569 aligncenter\" src=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/content-concept-illustration_114360-1483.jpg\" alt=\"\" width=\"626\" height=\"626\" srcset=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/content-concept-illustration_114360-1483.jpg 626w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/content-concept-illustration_114360-1483-300x300.jpg 300w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/content-concept-illustration_114360-1483-150x150.jpg 150w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/content-concept-illustration_114360-1483-420x420.jpg 420w\" sizes=\"auto, (max-width: 626px) 100vw, 626px\" \/><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Esta es una de las estrategias que presenta <a href=\"https:\/\/atrevete.academy\/blog\/inboundizacion-inbound-marketing-con-efecto-inmediato\/\"><strong>el Inbound Marketing<\/strong> <\/a>que ayudan a enfrentar momentos como en los que nos encontramos viviendo <strong>manteniendo la relaci\u00f3n con el clientes o leads con informaci\u00f3n necesaria<\/strong> para que se mantengan activos con la marca.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">De esta manera no solo el usuario se encuentra informado sobre los productos y\/o servicios de las marcas, sino que tambi\u00e9n <strong>buscan incentivar las compras online<\/strong> sin tener que salir de casa.<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<blockquote>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Recuerden: <a href=\"https:\/\/atrevete.academy\/blog\/yomequedoencasa-el-hashtag-que-combate-al-coronavirus\/\">#YoMeQuedoEnCasa<\/a><\/span><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/atrevete.academy\/taller-publicidad-en-facebook-y-chatbot\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2282 size-full\" src=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage.jpg\" alt=\"\" width=\"1920\" height=\"960\" srcset=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage.jpg 1920w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-300x150.jpg 300w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-1024x512.jpg 1024w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-768x384.jpg 768w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-1536x768.jpg 1536w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-696x348.jpg 696w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-1068x534.jpg 1068w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/09\/Banner-Fanpage-840x420.jpg 840w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Para ello, una de las opciones que han optado por emplear las empresas son a trav\u00e9s de <strong style=\"font-weight: 400;\">la compra de productos a precios reducido<\/strong> con la <strong><span style=\"font-weight: 400;\">opci\u00f3n de \u201c<\/span>apartarlo<span style=\"font-weight: 400;\">\u201d,<\/span><\/strong>\u00a0<strong>moment\u00e1neamente<\/strong>, hasta que se vuelva habilitar la movilizaci\u00f3n y reci\u00e9n puedan hacer los enviados a los clientes entreg\u00e1ndoles sus productos.<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Es m\u00e1s, se dice que <strong>el e-commerce<\/strong> va a llegar a <strong>crecer hasta un 50%<\/strong> desde ahora mismo porque una de las soluciones que se est\u00e1n dando, incluyendo el comercio de productos alimenticios, es <strong>el delivery<\/strong> de dichos productos sin costo alguno; con la finalidad de, que las personas eviten de salir de sus casas, se contagien y contagien a los dem\u00e1s.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Esta soluci\u00f3n es de<strong> ayuda m\u00fatua<\/strong> tanto para comerciantes o empresas como para los clientes que la solicitan, haciendo frente a un nuevo obst\u00e1culo que ha surgido.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Esta informaci\u00f3n es corroborada por <strong>Niubiz<\/strong>, quienes hab\u00edan informado que<strong> el comercio electr\u00f3nico hab\u00eda incrementado<\/strong> obteniendo una cantidad mayor al de 10 millones de soles, los primeros 7 d\u00edas iniciada la cuarentena. Adem\u00e1s, se cree que las personas que nunca han empleado este<strong> tipo de comercio electr\u00f3nico<\/strong> lo empleen en la actualidad obligatoriamente para facilitar el nuevo estilo de vida que nos ha tocado vivir.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1570 aligncenter\" src=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/shopping-e-commerce-isometric-composition-with-conceptual-image-phone-items-top-touchscreen-vector-illustration_1284-30744.jpg\" alt=\"\" width=\"626\" height=\"525\" srcset=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/shopping-e-commerce-isometric-composition-with-conceptual-image-phone-items-top-touchscreen-vector-illustration_1284-30744.jpg 626w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/shopping-e-commerce-isometric-composition-with-conceptual-image-phone-items-top-touchscreen-vector-illustration_1284-30744-300x252.jpg 300w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/shopping-e-commerce-isometric-composition-with-conceptual-image-phone-items-top-touchscreen-vector-illustration_1284-30744-501x420.jpg 501w\" sizes=\"auto, (max-width: 626px) 100vw, 626px\" \/>\u00a0<\/span><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"En_conclusion\"><\/span><span style=\"font-weight: 400;\">En conclusi\u00f3n,<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Hasta el momento existen varias soluciones que las empresas y empresarios, que se dedican <strong>al e-commerce<\/strong>, pueden optar para ejecutarlas frente a la crisis en la que nos encontramos. Mejor a\u00fan, haciendo uso de las estrategias de<strong> Inbound Marketing<\/strong>; en el cual, <strong>no es necesario de emplear publicidad pagada<\/strong> solventando tu negocio a trav\u00e9s de las plataformas digitales mediante tr\u00e1fico org\u00e1nico.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/atrevete.academy\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-813 size-full\" src=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/12\/bannerblog-01-scaled.png\" alt=\"tendencias redes sociales\" width=\"2048\" height=\"253\" srcset=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/12\/bannerblog-01-scaled.png 2048w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/12\/bannerblog-01-300x37.png 300w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/12\/bannerblog-01-1024x127.png 1024w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/12\/bannerblog-01-768x95.png 768w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/12\/bannerblog-01-1536x190.png 1536w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/12\/bannerblog-01-696x86.png 696w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/12\/bannerblog-01-1068x132.png 1068w, https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2019\/12\/bannerblog-01-1920x237.png 1920w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos estamos acercando al mes desde que entramos en aislamiento social obligatorio a causa de la llegada del coronavirus al pa\u00eds y, a consecuencia de ello, muchas personas que se encuentran en el sector del e-commerce, tanto para una empresa grande como para una independiente, se preguntan \u00bfc\u00f3mo pueden seguir incrementando o manteniendo sus ventas [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,21],"tags":[],"class_list":{"0":"post-1567","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-emprendimiento","8":"category-tendencias"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El E-Commerce en tiempos de Coronavirus - BLOG |<\/title>\n<meta name=\"description\" content=\"Conoce como la situaci\u00f3n del e-commerce (compra y venta online) ha sabido enfrentar la crisis del coronavirus ayudando a empresarios y a clientes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El E-Commerce en tiempos de Coronavirus - BLOG |\" \/>\n<meta property=\"og:description\" content=\"Conoce como la situaci\u00f3n del e-commerce (compra y venta online) ha sabido enfrentar la crisis del coronavirus ayudando a empresarios y a clientes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"BLOG |\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/atrevete.academy\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T16:49:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-04T00:37:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/E-commerce-web-development.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Atrevete Academia de Marketing Digital\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Atrevete Academia de Marketing Digital\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/\",\"url\":\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/\",\"name\":\"El E-Commerce en tiempos de Coronavirus - BLOG |\",\"isPartOf\":{\"@id\":\"https:\/\/atrevete.academy\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/E-commerce-web-development.png\",\"datePublished\":\"2020-04-15T16:49:39+00:00\",\"dateModified\":\"2020-11-04T00:37:54+00:00\",\"author\":{\"@id\":\"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/bb788b3a3a7e028ab3e0ef0bee458530\"},\"description\":\"Conoce como la situaci\u00f3n del e-commerce (compra y venta online) ha sabido enfrentar la crisis del coronavirus ayudando a empresarios y a clientes.\",\"breadcrumb\":{\"@id\":\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#primaryimage\",\"url\":\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/E-commerce-web-development.png\",\"contentUrl\":\"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/E-commerce-web-development.png\",\"width\":1650,\"height\":536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/atrevete.academy\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El E-Commerce en tiempos de Coronavirus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/atrevete.academy\/blog\/#website\",\"url\":\"https:\/\/atrevete.academy\/blog\/\",\"name\":\"BLOG |\",\"description\":\"Atr\u00e9vete Academia de Marketing Digital\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/atrevete.academy\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/bb788b3a3a7e028ab3e0ef0bee458530\",\"name\":\"Atrevete Academia de Marketing Digital\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2aa8c69a94e65335eb5772ab1a3e4e029bd82daac9574263c5505cd6afa2c377?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2aa8c69a94e65335eb5772ab1a3e4e029bd82daac9574263c5505cd6afa2c377?s=96&d=mm&r=g\",\"caption\":\"Atrevete Academia de Marketing Digital\"},\"description\":\"Atr\u00e9vete Academia de Marketing Digital busca ser tu aliado a la hora de aprender y aplicar las nuevas t\u00e9cnicas del Marketing Digital que te permitir\u00e1n entender a tus clientes y as\u00ed realizar estrategias efectivas que te ayudar\u00e1n a potenciar tus habilidades y las de tu empresa.\",\"sameAs\":[\"https:\/\/www.facebook.com\/atrevete.academy\/\",\"https:\/\/www.instagram.com\/atrevete_academy\/\"],\"url\":\"https:\/\/atrevete.academy\/blog\/author\/atrevete-academia-de-marketing-digital\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El E-Commerce en tiempos de Coronavirus - BLOG |","description":"Conoce como la situaci\u00f3n del e-commerce (compra y venta online) ha sabido enfrentar la crisis del coronavirus ayudando a empresarios y a clientes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/","og_locale":"es_ES","og_type":"article","og_title":"El E-Commerce en tiempos de Coronavirus - BLOG |","og_description":"Conoce como la situaci\u00f3n del e-commerce (compra y venta online) ha sabido enfrentar la crisis del coronavirus ayudando a empresarios y a clientes.","og_url":"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/","og_site_name":"BLOG |","article_author":"https:\/\/www.facebook.com\/atrevete.academy\/","article_published_time":"2020-04-15T16:49:39+00:00","article_modified_time":"2020-11-04T00:37:54+00:00","og_image":[{"width":1650,"height":536,"url":"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/E-commerce-web-development.png","type":"image\/png"}],"author":"Atrevete Academia de Marketing Digital","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Atrevete Academia de Marketing Digital","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/","url":"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/","name":"El E-Commerce en tiempos de Coronavirus - BLOG |","isPartOf":{"@id":"https:\/\/atrevete.academy\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/E-commerce-web-development.png","datePublished":"2020-04-15T16:49:39+00:00","dateModified":"2020-11-04T00:37:54+00:00","author":{"@id":"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/bb788b3a3a7e028ab3e0ef0bee458530"},"description":"Conoce como la situaci\u00f3n del e-commerce (compra y venta online) ha sabido enfrentar la crisis del coronavirus ayudando a empresarios y a clientes.","breadcrumb":{"@id":"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#primaryimage","url":"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/E-commerce-web-development.png","contentUrl":"https:\/\/atrevete.academy\/blog\/wp-content\/uploads\/2020\/04\/E-commerce-web-development.png","width":1650,"height":536},{"@type":"BreadcrumbList","@id":"https:\/\/atrevete.academy\/blog\/el-e-commerce-en-tiempos-de-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/atrevete.academy\/blog\/"},{"@type":"ListItem","position":2,"name":"El E-Commerce en tiempos de Coronavirus"}]},{"@type":"WebSite","@id":"https:\/\/atrevete.academy\/blog\/#website","url":"https:\/\/atrevete.academy\/blog\/","name":"BLOG |","description":"Atr\u00e9vete Academia de Marketing Digital","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atrevete.academy\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/bb788b3a3a7e028ab3e0ef0bee458530","name":"Atrevete Academia de Marketing Digital","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/atrevete.academy\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2aa8c69a94e65335eb5772ab1a3e4e029bd82daac9574263c5505cd6afa2c377?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2aa8c69a94e65335eb5772ab1a3e4e029bd82daac9574263c5505cd6afa2c377?s=96&d=mm&r=g","caption":"Atrevete Academia de Marketing Digital"},"description":"Atr\u00e9vete Academia de Marketing Digital busca ser tu aliado a la hora de aprender y aplicar las nuevas t\u00e9cnicas del Marketing Digital que te permitir\u00e1n entender a tus clientes y as\u00ed realizar estrategias efectivas que te ayudar\u00e1n a potenciar tus habilidades y las de tu empresa.","sameAs":["https:\/\/www.facebook.com\/atrevete.academy\/","https:\/\/www.instagram.com\/atrevete_academy\/"],"url":"https:\/\/atrevete.academy\/blog\/author\/atrevete-academia-de-marketing-digital\/"}]}},"_links":{"self":[{"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/posts\/1567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/comments?post=1567"}],"version-history":[{"count":4,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/posts\/1567\/revisions"}],"predecessor-version":[{"id":2565,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/posts\/1567\/revisions\/2565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/media\/1572"}],"wp:attachment":[{"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/media?parent=1567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/categories?post=1567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atrevete.academy\/blog\/wp-json\/wp\/v2\/tags?post=1567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}